{"id":25,"name":"Maurizio De Angelis","url":"","description":"","link":"https:\/\/collectoapp.com\/en\/blog\/author\/maurizio-de-angelis\/","slug":"maurizio-de-angelis","avatar_urls":{"24":"https:\/\/collectoapp.com\/wp-content\/litespeed\/avatar\/c401506296b8f69b149136e392a53c1a.jpg?ver=1778218636","48":"https:\/\/collectoapp.com\/wp-content\/litespeed\/avatar\/007315e82f868d969ed5841035940bc0.jpg?ver=1778218636","96":"https:\/\/collectoapp.com\/wp-content\/litespeed\/avatar\/b2d5d5810cad4f976b494102895fd71e.jpg?ver=1778218636"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maurizio De Angelis, Autore presso collecto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/collectoapp.com\/en\/blog\/author\/maurizio-de-angelis\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Maurizio De Angelis, Autore presso collecto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/collectoapp.com\/en\/blog\/author\/maurizio-de-angelis\/\" \/>\n<meta property=\"og:site_name\" content=\"collecto\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/169eee90412308c008e5a7d4143746719ee0c1f26b7170cd38b6486e87337ede?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/collectoapp.com\\\/en\\\/blog\\\/author\\\/maurizio-de-angelis\\\/\",\"url\":\"https:\\\/\\\/collectoapp.com\\\/en\\\/blog\\\/author\\\/maurizio-de-angelis\\\/\",\"name\":\"Maurizio De Angelis, Autore presso collecto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/collectoapp.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/collectoapp.com\\\/en\\\/blog\\\/author\\\/maurizio-de-angelis\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/collectoapp.com\\\/en\\\/blog\\\/author\\\/maurizio-de-angelis\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/collectoapp.com\\\/en\\\/blog\\\/author\\\/maurizio-de-angelis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/collectoapp.com\\\/en\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archivi per Maurizio De Angelis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/collectoapp.com\\\/#website\",\"url\":\"https:\\\/\\\/collectoapp.com\\\/\",\"name\":\"collecto\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/collectoapp.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/collectoapp.com\\\/#\\\/schema\\\/person\\\/b591fb687cf892bb8eeb4f6665914758\",\"name\":\"Maurizio De Angelis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/collectoapp.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b2d5d5810cad4f976b494102895fd71e.jpg?ver=1778218636\",\"url\":\"https:\\\/\\\/collectoapp.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b2d5d5810cad4f976b494102895fd71e.jpg?ver=1778218636\",\"contentUrl\":\"https:\\\/\\\/collectoapp.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b2d5d5810cad4f976b494102895fd71e.jpg?ver=1778218636\",\"caption\":\"Maurizio De Angelis\"},\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/collectoapp.com\\\/en\\\/blog\\\/author\\\/maurizio-de-angelis\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maurizio De Angelis, Autore presso collecto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/collectoapp.com\/en\/blog\/author\/maurizio-de-angelis\/","og_locale":"en_US","og_type":"profile","og_title":"Maurizio De Angelis, Autore presso collecto","og_url":"https:\/\/collectoapp.com\/en\/blog\/author\/maurizio-de-angelis\/","og_site_name":"collecto","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/169eee90412308c008e5a7d4143746719ee0c1f26b7170cd38b6486e87337ede?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/collectoapp.com\/en\/blog\/author\/maurizio-de-angelis\/","url":"https:\/\/collectoapp.com\/en\/blog\/author\/maurizio-de-angelis\/","name":"Maurizio De Angelis, Autore presso collecto","isPartOf":{"@id":"https:\/\/collectoapp.com\/#website"},"breadcrumb":{"@id":"https:\/\/collectoapp.com\/en\/blog\/author\/maurizio-de-angelis\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/collectoapp.com\/en\/blog\/author\/maurizio-de-angelis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/collectoapp.com\/en\/blog\/author\/maurizio-de-angelis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/collectoapp.com\/en\/homepage\/"},{"@type":"ListItem","position":2,"name":"Archivi per Maurizio De Angelis"}]},{"@type":"WebSite","@id":"https:\/\/collectoapp.com\/#website","url":"https:\/\/collectoapp.com\/","name":"collecto","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/collectoapp.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/collectoapp.com\/#\/schema\/person\/b591fb687cf892bb8eeb4f6665914758","name":"Maurizio De Angelis","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/collectoapp.com\/wp-content\/litespeed\/avatar\/b2d5d5810cad4f976b494102895fd71e.jpg?ver=1778218636","url":"https:\/\/collectoapp.com\/wp-content\/litespeed\/avatar\/b2d5d5810cad4f976b494102895fd71e.jpg?ver=1778218636","contentUrl":"https:\/\/collectoapp.com\/wp-content\/litespeed\/avatar\/b2d5d5810cad4f976b494102895fd71e.jpg?ver=1778218636","caption":"Maurizio De Angelis"},"mainEntityOfPage":{"@id":"https:\/\/collectoapp.com\/en\/blog\/author\/maurizio-de-angelis\/"}}]}},"elementor_introduction":"","_links":{"self":[{"href":"https:\/\/collectoapp.com\/en\/wp-json\/wp\/v2\/users\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collectoapp.com\/en\/wp-json\/wp\/v2\/users"}]}}