{"id":27,"name":"Mucciaccia Gallery","url":"","description":"","link":"https:\/\/collectoapp.com\/en\/blog\/author\/mucciaccia-gallery\/","slug":"mucciaccia-gallery","avatar_urls":{"24":"https:\/\/collectoapp.com\/wp-content\/litespeed\/avatar\/27d2e31bd2bcfdb737bbc35b191d94cc.jpg?ver=1778218638","48":"https:\/\/collectoapp.com\/wp-content\/litespeed\/avatar\/d36f2a74e5c610dc89de787efde50986.jpg?ver=1778218638","96":"https:\/\/collectoapp.com\/wp-content\/litespeed\/avatar\/83c692248d7afe96c9c692519cd1059f.jpg?ver=1778218639"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mucciaccia Gallery, Autore presso collecto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/collectoapp.com\/en\/blog\/author\/mucciaccia-gallery\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Mucciaccia Gallery, Autore presso collecto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/collectoapp.com\/en\/blog\/author\/mucciaccia-gallery\/\" \/>\n<meta property=\"og:site_name\" content=\"collecto\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/d7d7b1456a70c6072d3949984a33f558449ad9493aa6a76d7a3b1dd5d296353b?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/collectoapp.com\\\/en\\\/blog\\\/author\\\/mucciaccia-gallery\\\/\",\"url\":\"https:\\\/\\\/collectoapp.com\\\/en\\\/blog\\\/author\\\/mucciaccia-gallery\\\/\",\"name\":\"Mucciaccia Gallery, Autore presso collecto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/collectoapp.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/collectoapp.com\\\/en\\\/blog\\\/author\\\/mucciaccia-gallery\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/collectoapp.com\\\/en\\\/blog\\\/author\\\/mucciaccia-gallery\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/collectoapp.com\\\/en\\\/blog\\\/author\\\/mucciaccia-gallery\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/collectoapp.com\\\/en\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archivi per Mucciaccia Gallery\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/collectoapp.com\\\/#website\",\"url\":\"https:\\\/\\\/collectoapp.com\\\/\",\"name\":\"collecto\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/collectoapp.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/collectoapp.com\\\/#\\\/schema\\\/person\\\/87d4c0a8a8f9513f18a0adb7e34f7e60\",\"name\":\"Mucciaccia Gallery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/collectoapp.com\\\/wp-content\\\/litespeed\\\/avatar\\\/83c692248d7afe96c9c692519cd1059f.jpg?ver=1778218639\",\"url\":\"https:\\\/\\\/collectoapp.com\\\/wp-content\\\/litespeed\\\/avatar\\\/83c692248d7afe96c9c692519cd1059f.jpg?ver=1778218639\",\"contentUrl\":\"https:\\\/\\\/collectoapp.com\\\/wp-content\\\/litespeed\\\/avatar\\\/83c692248d7afe96c9c692519cd1059f.jpg?ver=1778218639\",\"caption\":\"Mucciaccia Gallery\"},\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/collectoapp.com\\\/en\\\/blog\\\/author\\\/mucciaccia-gallery\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mucciaccia Gallery, Autore presso collecto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/collectoapp.com\/en\/blog\/author\/mucciaccia-gallery\/","og_locale":"en_US","og_type":"profile","og_title":"Mucciaccia Gallery, Autore presso collecto","og_url":"https:\/\/collectoapp.com\/en\/blog\/author\/mucciaccia-gallery\/","og_site_name":"collecto","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/d7d7b1456a70c6072d3949984a33f558449ad9493aa6a76d7a3b1dd5d296353b?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/collectoapp.com\/en\/blog\/author\/mucciaccia-gallery\/","url":"https:\/\/collectoapp.com\/en\/blog\/author\/mucciaccia-gallery\/","name":"Mucciaccia Gallery, Autore presso collecto","isPartOf":{"@id":"https:\/\/collectoapp.com\/#website"},"breadcrumb":{"@id":"https:\/\/collectoapp.com\/en\/blog\/author\/mucciaccia-gallery\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/collectoapp.com\/en\/blog\/author\/mucciaccia-gallery\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/collectoapp.com\/en\/blog\/author\/mucciaccia-gallery\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/collectoapp.com\/en\/homepage\/"},{"@type":"ListItem","position":2,"name":"Archivi per Mucciaccia Gallery"}]},{"@type":"WebSite","@id":"https:\/\/collectoapp.com\/#website","url":"https:\/\/collectoapp.com\/","name":"collecto","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/collectoapp.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/collectoapp.com\/#\/schema\/person\/87d4c0a8a8f9513f18a0adb7e34f7e60","name":"Mucciaccia Gallery","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/collectoapp.com\/wp-content\/litespeed\/avatar\/83c692248d7afe96c9c692519cd1059f.jpg?ver=1778218639","url":"https:\/\/collectoapp.com\/wp-content\/litespeed\/avatar\/83c692248d7afe96c9c692519cd1059f.jpg?ver=1778218639","contentUrl":"https:\/\/collectoapp.com\/wp-content\/litespeed\/avatar\/83c692248d7afe96c9c692519cd1059f.jpg?ver=1778218639","caption":"Mucciaccia Gallery"},"mainEntityOfPage":{"@id":"https:\/\/collectoapp.com\/en\/blog\/author\/mucciaccia-gallery\/"}}]}},"elementor_introduction":"","_links":{"self":[{"href":"https:\/\/collectoapp.com\/en\/wp-json\/wp\/v2\/users\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collectoapp.com\/en\/wp-json\/wp\/v2\/users"}]}}